{"id":608,"date":"2021-08-24T09:47:38","date_gmt":"2021-08-24T14:47:38","guid":{"rendered":"https:\/\/ratpark.studio\/?p=608"},"modified":"2021-08-24T09:54:45","modified_gmt":"2021-08-24T14:54:45","slug":"a-menos-que","status":"publish","type":"post","link":"https:\/\/ratpark.studio\/es\/a-menos-que\/","title":{"rendered":"A menos que&#8230;"},"content":{"rendered":"\n<p class=\"has-drop-cap wp-block-paragraph\" id=\"unless\">Desde ni\u00f1os, al menos mi generaci\u00f3n de los 80\u00b4 en adelante, hemos estado conscientes de que el planeta est\u00e1 en un cambio emocionante pero problem\u00e1tico. Quienes tuvimos una chispa de privilegio crecimos en un entorno de r\u00e1pidos desarrollos en la tecnolog\u00eda, y gracias a esto muchos de nosotros pudimos desarrollar nuestras carreras alrededor de estos desarrollos, especialmente los computadores e internet.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No deja de ser asombroso, como en solo un cambio generacional los hijos (privilegiados) de esta era hemos sido capaces de consumir una cantidad excepcional de informaci\u00f3n y conocimiento, mucho m\u00e1s que cualquiera de nuestros ancestros. As\u00ed, nuestra educaci\u00f3n tambi\u00e9n ha sido dislocada, cambiando los patrones cl\u00e1sicos del aula a la necesidad de una formaci\u00f3n aut\u00f3noma, y dirigida a las necesidades y b\u00fasquedas individuales. La experticia ya no la est\u00e1 dando la validaci\u00f3n acad\u00e9mica. Los milenials guardamos los diplomas en el closet.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero el otro punto asombroso es que somos la primera generaci\u00f3n m\u00e1s pobre que la anterior. Lo que genera una paradoja preciosa. \u00bfPor qu\u00e9 el grupo m\u00e1s capaz en la historia de la humanidad tiene menos ingresos que sus padres?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y entonces \u00bfQue tiene esto que ver con la pobreza en general?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La econom\u00eda mundial no ha dejado de crecer exponencialmente desde la revoluci\u00f3n industrial, la caldera del motor de vapor no ha dejado de quemar carb\u00f3n para alimentar nuestras necesidades energ\u00e9ticas. La destilaci\u00f3n del petr\u00f3leo y su combusti\u00f3n nos ha permitido movilizarnos, y mucho m\u00e1s. La extracci\u00f3n de minerales como el colt\u00e1n nos permiten escribir nuestros pensamientos, visualizarlos y viralizarlos. La agricultura masiva permite el consumo de alimentos m\u00e1s al alcance. La contrataci\u00f3n en condiciones de explotaci\u00f3n nos garantiza ropa y bienes baratos. La devastaci\u00f3n de los ecosistemas y de la ruptura de la vida se refleja en nuestra propia ansiedad, depresi\u00f3n y en el desbalance mental de cada capa de la sociedad. A menos que\u2026&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como dijo el Lorax, a menos que alguien como t\u00fa le importe.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El punto es que quienes hemos tenido el privilegio de crecer en un entorno de conocimiento, ya sea acad\u00e9mico o emp\u00edrico, compartimos una responsabilidad com\u00fan generacional.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenemos que salir de la dificultad econ\u00f3mica entendiendo las nuevas necesidades, din\u00e1micas y prioridades y sobre todo, tenemos que salir juntos, entenderlo juntos y prosperar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Usar la imaginaci\u00f3n para resolver los problemas actuales del mundo. Pues es que no hay de otra, los humanos estamos hechos para imaginar y conectar, y tal vez podamos dise\u00f1ar una ruta para no caer en el hueco del antropoceno. A su vez puede que esta sea la mayor oportunidad de nuestra existencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Procurar, en la construcci\u00f3n de esta riqueza, entender los l\u00edmites de nuestro entorno biol\u00f3gico y buscar en paralelo su respeto y progreso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00e1cil decirlo, aunque creo posible que al menos plantemos semillas. Para mi el sue\u00f1o es volver al campo mientras nos despegamos de las redes obsoletas de agua, energ\u00eda y comida, demostrarnos sostenibles desde los propios n\u00facleos, y generar riqueza a trav\u00e9s de la cultivaci\u00f3n de la experticia en nuestras \u00e1reas de inter\u00e9s, generar valor a trav\u00e9s de nuestro conocimiento. Dise\u00f1ar sistemas, y reciclar los que est\u00e1n sirviendo para aportar.&nbsp; Y en \u00faltimas ser prueba de que podemos ser otra cosa tal vez mejor.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La descentralizaci\u00f3n del dinero, NFTs, Bitcoins y dem\u00e1s, podr\u00e1n ser clave en esta redistribuci\u00f3n del valor y la riqueza.<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Desde ni\u00f1os, al menos mi generaci\u00f3n de los 80\u00b4 en adelante, hemos estado conscientes de que el planeta est\u00e1 en un cambio emocionante pero problem\u00e1tico. Quienes tuvimos una chispa de privilegio crecimos en un entorno de r\u00e1pidos desarrollos en la tecnolog\u00eda, y gracias a esto muchos de nosotros pudimos desarrollar nuestras carreras alrededor de estos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"793","footnotes":""},"categories":[13,14],"tags":[15,16,17],"class_list":["post-608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-creatividad","category-sostenibilidad","tag-antropoceno","tag-lorax","tag-responsabilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A menos que... - Rat Park - Branding para la Sostenibilidad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ratpark.studio\/es\/a-menos-que\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A menos que... - Rat Park - Branding para la Sostenibilidad\" \/>\n<meta property=\"og:description\" content=\"Desde ni\u00f1os, al menos mi generaci\u00f3n de los 80\u00b4 en adelante, hemos estado conscientes de que el planeta est\u00e1 en un cambio emocionante pero problem\u00e1tico. Quienes tuvimos una chispa de privilegio crecimos en un entorno de r\u00e1pidos desarrollos en la tecnolog\u00eda, y gracias a esto muchos de nosotros pudimos desarrollar nuestras carreras alrededor de estos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ratpark.studio\/es\/a-menos-que\/\" \/>\n<meta property=\"og:site_name\" content=\"Rat Park - Branding para la Sostenibilidad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/parqueratuno\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-24T14:47:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-24T14:54:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ratpark.studio\/wp-content\/uploads\/2021\/08\/unless-the-lorax.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"822\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Germ\u00e1n Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Germ\u00e1n Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/\"},\"author\":{\"name\":\"Germ\u00e1n Silva\",\"@id\":\"https:\\\/\\\/ratpark.studio\\\/#\\\/schema\\\/person\\\/75c7e7d09c6febc57f63c0f40e930b89\"},\"headline\":\"A menos que&#8230;\",\"datePublished\":\"2021-08-24T14:47:38+00:00\",\"dateModified\":\"2021-08-24T14:54:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/\"},\"wordCount\":617,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ratpark.studio\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/unless-the-lorax.jpg\",\"keywords\":[\"antropoceno\",\"lorax\",\"responsabilidad\"],\"articleSection\":[\"creatividad\",\"sostenibilidad\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/\",\"url\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/\",\"name\":\"A menos que... - Rat Park - Branding para la Sostenibilidad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ratpark.studio\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/unless-the-lorax.jpg\",\"datePublished\":\"2021-08-24T14:47:38+00:00\",\"dateModified\":\"2021-08-24T14:54:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ratpark.studio\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/unless-the-lorax.jpg\",\"contentUrl\":\"https:\\\/\\\/ratpark.studio\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/unless-the-lorax.jpg\",\"width\":1600,\"height\":822,\"caption\":\"El Lorax - Dr. Seuss\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ratpark.studio\\\/a-menos-que\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ratpark.studio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A menos que&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ratpark.studio\\\/#website\",\"url\":\"https:\\\/\\\/ratpark.studio\\\/\",\"name\":\"Rat Park - Branding para la Sostenibilidad\",\"description\":\"Somos una agencia creadora de marcas. Ofrecemos estrategias de marca, dise\u00f1o de logos y sistemas de identidad para iniciativas que trabajan por un mundo mejor.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ratpark.studio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ratpark.studio\\\/#organization\",\"name\":\"Rat Park Studio\",\"url\":\"https:\\\/\\\/ratpark.studio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/ratpark.studio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ratpark.studio\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ProfileFaceBook.jpg\",\"contentUrl\":\"https:\\\/\\\/ratpark.studio\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ProfileFaceBook.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"Rat Park Studio\"},\"image\":{\"@id\":\"https:\\\/\\\/ratpark.studio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/parqueratuno\",\"https:\\\/\\\/www.instagram.com\\\/ratparkstudio\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rat-park-studio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ratpark.studio\\\/#\\\/schema\\\/person\\\/75c7e7d09c6febc57f63c0f40e930b89\",\"name\":\"Germ\u00e1n Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfb4cb3927bae378d33727d4d33606db06ee37d8bcf890cc4928711212da4db8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfb4cb3927bae378d33727d4d33606db06ee37d8bcf890cc4928711212da4db8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfb4cb3927bae378d33727d4d33606db06ee37d8bcf890cc4928711212da4db8?s=96&d=mm&r=g\",\"caption\":\"Germ\u00e1n Silva\"},\"sameAs\":[\"https:\\\/\\\/ratpark.studio\"],\"url\":\"https:\\\/\\\/ratpark.studio\\\/es\\\/author\\\/german\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A menos que... - Rat Park - Branding para la Sostenibilidad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ratpark.studio\/es\/a-menos-que\/","og_locale":"es_ES","og_type":"article","og_title":"A menos que... - Rat Park - Branding para la Sostenibilidad","og_description":"Desde ni\u00f1os, al menos mi generaci\u00f3n de los 80\u00b4 en adelante, hemos estado conscientes de que el planeta est\u00e1 en un cambio emocionante pero problem\u00e1tico. Quienes tuvimos una chispa de privilegio crecimos en un entorno de r\u00e1pidos desarrollos en la tecnolog\u00eda, y gracias a esto muchos de nosotros pudimos desarrollar nuestras carreras alrededor de estos [&hellip;]","og_url":"https:\/\/ratpark.studio\/es\/a-menos-que\/","og_site_name":"Rat Park - Branding para la Sostenibilidad","article_publisher":"https:\/\/www.facebook.com\/parqueratuno","article_published_time":"2021-08-24T14:47:38+00:00","article_modified_time":"2021-08-24T14:54:45+00:00","og_image":[{"width":1600,"height":822,"url":"https:\/\/ratpark.studio\/wp-content\/uploads\/2021\/08\/unless-the-lorax.jpg","type":"image\/jpeg"}],"author":"Germ\u00e1n Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Germ\u00e1n Silva","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ratpark.studio\/a-menos-que\/#article","isPartOf":{"@id":"https:\/\/ratpark.studio\/a-menos-que\/"},"author":{"name":"Germ\u00e1n Silva","@id":"https:\/\/ratpark.studio\/#\/schema\/person\/75c7e7d09c6febc57f63c0f40e930b89"},"headline":"A menos que&#8230;","datePublished":"2021-08-24T14:47:38+00:00","dateModified":"2021-08-24T14:54:45+00:00","mainEntityOfPage":{"@id":"https:\/\/ratpark.studio\/a-menos-que\/"},"wordCount":617,"commentCount":0,"publisher":{"@id":"https:\/\/ratpark.studio\/#organization"},"image":{"@id":"https:\/\/ratpark.studio\/a-menos-que\/#primaryimage"},"thumbnailUrl":"https:\/\/ratpark.studio\/wp-content\/uploads\/2021\/08\/unless-the-lorax.jpg","keywords":["antropoceno","lorax","responsabilidad"],"articleSection":["creatividad","sostenibilidad"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ratpark.studio\/a-menos-que\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ratpark.studio\/a-menos-que\/","url":"https:\/\/ratpark.studio\/a-menos-que\/","name":"A menos que... - Rat Park - Branding para la Sostenibilidad","isPartOf":{"@id":"https:\/\/ratpark.studio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ratpark.studio\/a-menos-que\/#primaryimage"},"image":{"@id":"https:\/\/ratpark.studio\/a-menos-que\/#primaryimage"},"thumbnailUrl":"https:\/\/ratpark.studio\/wp-content\/uploads\/2021\/08\/unless-the-lorax.jpg","datePublished":"2021-08-24T14:47:38+00:00","dateModified":"2021-08-24T14:54:45+00:00","breadcrumb":{"@id":"https:\/\/ratpark.studio\/a-menos-que\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ratpark.studio\/a-menos-que\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/ratpark.studio\/a-menos-que\/#primaryimage","url":"https:\/\/ratpark.studio\/wp-content\/uploads\/2021\/08\/unless-the-lorax.jpg","contentUrl":"https:\/\/ratpark.studio\/wp-content\/uploads\/2021\/08\/unless-the-lorax.jpg","width":1600,"height":822,"caption":"El Lorax - Dr. Seuss"},{"@type":"BreadcrumbList","@id":"https:\/\/ratpark.studio\/a-menos-que\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ratpark.studio\/"},{"@type":"ListItem","position":2,"name":"A menos que&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/ratpark.studio\/#website","url":"https:\/\/ratpark.studio\/","name":"Rat Park - Branding para la Sostenibilidad","description":"Somos una agencia creadora de marcas. Ofrecemos estrategias de marca, dise\u00f1o de logos y sistemas de identidad para iniciativas que trabajan por un mundo mejor.","publisher":{"@id":"https:\/\/ratpark.studio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ratpark.studio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/ratpark.studio\/#organization","name":"Rat Park Studio","url":"https:\/\/ratpark.studio\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/ratpark.studio\/#\/schema\/logo\/image\/","url":"https:\/\/ratpark.studio\/wp-content\/uploads\/2022\/06\/ProfileFaceBook.jpg","contentUrl":"https:\/\/ratpark.studio\/wp-content\/uploads\/2022\/06\/ProfileFaceBook.jpg","width":1080,"height":1080,"caption":"Rat Park Studio"},"image":{"@id":"https:\/\/ratpark.studio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/parqueratuno","https:\/\/www.instagram.com\/ratparkstudio\/","https:\/\/www.linkedin.com\/company\/rat-park-studio\/"]},{"@type":"Person","@id":"https:\/\/ratpark.studio\/#\/schema\/person\/75c7e7d09c6febc57f63c0f40e930b89","name":"Germ\u00e1n Silva","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/cfb4cb3927bae378d33727d4d33606db06ee37d8bcf890cc4928711212da4db8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cfb4cb3927bae378d33727d4d33606db06ee37d8bcf890cc4928711212da4db8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfb4cb3927bae378d33727d4d33606db06ee37d8bcf890cc4928711212da4db8?s=96&d=mm&r=g","caption":"Germ\u00e1n Silva"},"sameAs":["https:\/\/ratpark.studio"],"url":"https:\/\/ratpark.studio\/es\/author\/german\/"}]}},"_links":{"self":[{"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/posts\/608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/comments?post=608"}],"version-history":[{"count":3,"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/posts\/608\/revisions"}],"predecessor-version":[{"id":612,"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/posts\/608\/revisions\/612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/media\/609"}],"wp:attachment":[{"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/media?parent=608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/categories?post=608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ratpark.studio\/es\/wp-json\/wp\/v2\/tags?post=608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}